{"id":19515,"date":"2020-05-27T19:52:25","date_gmt":"2020-05-27T17:52:25","guid":{"rendered":"https:\/\/test.fgc.cat\/?post_type=fgc-faq&#038;p=19515"},"modified":"2023-11-16T14:58:43","modified_gmt":"2023-11-16T13:58:43","slug":"cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio","status":"publish","type":"fgc-faq","link":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/","title":{"rendered":"\u00bfCu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio?"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-23904\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg\" alt=\"\" width=\"1029\" height=\"477\" \/><\/p>\n<table width=\"1397\">\n<tbody>\n<tr>\n<td width=\"1397\">Para acceder a los servicios de transporte p\u00fablico, la persona usuaria debe disponer de un billete adecuado de conformidad con las condiciones aplicables en cada momento.Se considera que la persona usuaria hace un uso indebido del servicio en los siguientes casos:<\/p>\n<p>a) El billete no se ha validado antes de viajar o acceder a los recintos delimitados.<br \/>\nb) La persona usuaria no dispone del billete o no puede mostrarlo cuando se le pide.<br \/>\nc) El billete ha caducado, es decir, cuando se utiliza fuera del plazo de validez temporal establecido en el contrato tipo o en las tarifas especiales.<br \/>\nd) Se trata de un billete de importe reducido y la persona que viaja no puede acreditar, con el carn\u00e9 correspondiente, el derecho de obtenerlo.<br \/>\ne) Se trata de un billete personalizado que no es de su titularidad.<br \/>\nf) El billete se utiliza fuera de la zona tarifaria correspondiente.<br \/>\ng) Se viaja con un t\u00edtulo de transporte que no es v\u00e1lido para las caracter\u00edsticas espec\u00edficas del desplazamiento o del viajero.<\/p>\n<p>Puede consultar el texto \u00edntegro de las condiciones de utilizaci\u00f3n en el siguiente enlace: <a href=\"https:\/\/www.fgc.cat\/atencio-al-client\/condicions-d-us\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fgc.cat\/es\/atencio-al-client\/condicions-d-us\/ <\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"featured_media":0,"template":"","faq-categories":[],"class_list":["post-19515","fgc-faq","type-fgc-faq","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FAQs: \u00bfcu\u00e1ndo hay un uso indebido del servicio? | FGC<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres saber cu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio? Consulta ahora las preguntas frecuentes (FAQs) de nuestra web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio?\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres saber cu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio? Consulta ahora las preguntas frecuentes (FAQs) de nuestra web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferrocarrils de la Generalitat de Catalunya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fgcferrocarrils\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T13:58:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FGC\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/\",\"name\":\"FAQs: \u00bfcu\u00e1ndo hay un uso indebido del servicio? | FGC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg\",\"datePublished\":\"2020-05-27T17:52:25+00:00\",\"dateModified\":\"2023-11-16T13:58:43+00:00\",\"description\":\"\u00bfQuieres saber cu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio? Consulta ahora las preguntas frecuentes (FAQs) de nuestra web.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faqs\",\"item\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/fgc-faq\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfCu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/\",\"name\":\"FGC\",\"description\":\"Ferrocarrils de la Generalitat de Catalunya\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#organization\",\"name\":\"Ferrocarrils de la Generalitat de Catalunya\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-FGC-square.png\",\"contentUrl\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-FGC-square.png\",\"width\":1024,\"height\":1024,\"caption\":\"Ferrocarrils de la Generalitat de Catalunya\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fgcferrocarrils\",\"https:\\\/\\\/x.com\\\/FGC\",\"https:\\\/\\\/www.instagram.com\\\/fgc.cat\\\/?hl=es\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/FGCferrocarrils\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FAQs: \u00bfcu\u00e1ndo hay un uso indebido del servicio? | FGC","description":"\u00bfQuieres saber cu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio? Consulta ahora las preguntas frecuentes (FAQs) de nuestra web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio?","og_description":"\u00bfQuieres saber cu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio? Consulta ahora las preguntas frecuentes (FAQs) de nuestra web.","og_url":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/","og_site_name":"Ferrocarrils de la Generalitat de Catalunya","article_publisher":"https:\/\/www.facebook.com\/fgcferrocarrils","article_modified_time":"2023-11-16T13:58:43+00:00","og_image":[{"url":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@FGC","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/","url":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/","name":"FAQs: \u00bfcu\u00e1ndo hay un uso indebido del servicio? | FGC","isPartOf":{"@id":"https:\/\/www.fgc.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/#primaryimage"},"image":{"@id":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg","datePublished":"2020-05-27T17:52:25+00:00","dateModified":"2023-11-16T13:58:43+00:00","description":"\u00bfQuieres saber cu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio? Consulta ahora las preguntas frecuentes (FAQs) de nuestra web.","breadcrumb":{"@id":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/#primaryimage","url":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg","contentUrl":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/OLESA-DE-MONTSERRAT-FGC-013-scaled-e1593182890161-300x139.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fgc.cat\/es\/fgc-faq\/cuando-se-considera-que-una-persona-usuaria-hace-un-uso-indebido-del-servicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fgc.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Faqs","item":"https:\/\/www.fgc.cat\/es\/fgc-faq\/"},{"@type":"ListItem","position":3,"name":"\u00bfCu\u00e1ndo se considera que una persona usuaria hace un uso indebido del servicio?"}]},{"@type":"WebSite","@id":"https:\/\/www.fgc.cat\/es\/#website","url":"https:\/\/www.fgc.cat\/es\/","name":"FGC","description":"Ferrocarrils de la Generalitat de Catalunya","publisher":{"@id":"https:\/\/www.fgc.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fgc.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fgc.cat\/es\/#organization","name":"Ferrocarrils de la Generalitat de Catalunya","url":"https:\/\/www.fgc.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fgc.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/logo-FGC-square.png","contentUrl":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/logo-FGC-square.png","width":1024,"height":1024,"caption":"Ferrocarrils de la Generalitat de Catalunya"},"image":{"@id":"https:\/\/www.fgc.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fgcferrocarrils","https:\/\/x.com\/FGC","https:\/\/www.instagram.com\/fgc.cat\/?hl=es","http:\/\/www.youtube.com\/user\/FGCferrocarrils"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/fgc-faq\/19515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/fgc-faq"}],"about":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/types\/fgc-faq"}],"version-history":[{"count":6,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/fgc-faq\/19515\/revisions"}],"predecessor-version":[{"id":46463,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/fgc-faq\/19515\/revisions\/46463"}],"wp:attachment":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/media?parent=19515"}],"wp:term":[{"taxonomy":"faq-categories","embeddable":true,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/faq-categories?post=19515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}