{"id":2773,"date":"2017-08-15T18:21:11","date_gmt":"2017-08-15T18:21:11","guid":{"rendered":"\/atencion-al-cliente\/condicions-d-us\/"},"modified":"2025-07-21T14:46:14","modified_gmt":"2025-07-21T12:46:14","slug":"condiciones-de-uso","status":"publish","type":"page","link":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/","title":{"rendered":"Condiciones de uso"},"content":{"rendered":"<section class=\"l-section wpb_row container breadcrumb2 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><pre><span><span><a href=\"https:\/\/www.fgc.cat\/es\/\">Portada<\/a><\/span><\/span><\/pre>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><!-- Row Backgrounds --><div class=\"upb_color\" data-bg-override=\"0\" data-bg-color=\"\" data-fadeout=\"\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"8.7.3\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"     data-hide-row=\" uvc_hidden-lg  uvc_hidden-ml  uvc_hidden-md  uvc_hidden-sm  uvc_hidden-xs  uvc_hidden-xsl \" ><\/div><section class=\"l-section wpb_row us_custom_b09c7e29 container breadcrumb2 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_fcc5f992 container formulari_responsive height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-4 wpb_column vc_column_container columna_izq\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style data-type=\"us_custom-css\">.client-links{list-style:none;padding-left:0;margin:0}.client-links li{list-style:none;padding-left:0; margin-left:0;padding-bottom:20px}.link-item{text-decoration:underline;color:#004c3f; display:inline-block;margin-bottom:0.3em}.client-links-wrapper ul{margin-left:0}.client-links-wrapper li{list-style:none;padding-left:0; margin-left:0}<\/style><style data-type=\"vc_shortcodes-custom-css\">.vc_custom_1590483353167{margin-top:36px!important}.vc_custom_1590483353167{margin-top:36px!important}.vc_custom_1590483353167{margin-top:36px!important}<\/style><section class=\"l-section wpb_row us_custom_b6a72ce1 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_b069dd80\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>\u00bfEN QU\u00c9 OS PODEMOS AYUDAR?<\/h2>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul class=\"client-links\">\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/consultas\/\" rel=\"noopener\">Formulario de Consultas<\/a><\/li>\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/reclamaciones\/\" rel=\"noopener\">Formulario de Quejas y reclamaciones<\/a><\/li>\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/sugerencias\/\" rel=\"noopener\">Formulario de Sugerencias y agradecimientos<\/a><\/li>\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/centros-presenciales\/\" rel=\"noopener\">Centros de atenci\u00f3n al cliente<\/a><\/li>\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/justificante-retraso\/\" rel=\"noopener\">Justificante de retraso<\/a><\/li>\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente-faq\/\" rel=\"noopener\">Preguntas frecuentes<\/a><\/li>\n<li><a class=\"link-item\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/\" rel=\"noopener\">Condiciones de uso<\/a><\/li>\n<li><a class=\"external-link\" href=\"https:\/\/www4.caixabank.es\/apl\/pagos\/index_es.html\" target=\"_blank\" rel=\"noopener\">Pago de percepciones m\u00ednimas<span aria-hidden=\"true\" class=\"icon icon-external\"><\/span><\/a><\/li>\n<li><a class=\"external-link\" href=\"https:\/\/web.gencat.cat\/es\/tramits\/tramits-temes\/Peticio-generica?category=72461610-a82c-11e3-a972-000c29052e2c\" target=\"_blank\" rel=\"noopener\">Acceso al tr\u00e1mite de peticiones gen\u00e9ricas de la Generalitat de Catalunya<span aria-hidden=\"true\" class=\"icon icon-external\"><\/span><br \/>\n<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<section class=\"l-section wpb_row us_custom_b6a72ce1 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_14cb6347\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"688\" height=\"414\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/faqs_aside_2x.jpg\" class=\"attachment-large size-large\" alt=\"Icono informacion\" loading=\"lazy\" srcset=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/faqs_aside_2x.jpg 688w, https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/faqs_aside_2x-600x361.jpg 600w, https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/faqs_aside_2x-300x181.jpg 300w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/div><\/div><div class=\"g-cols wpb_row us_custom_718cace0 via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_15ad39e0\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_632d41e4 has_text_color\"><div class=\"wpb_wrapper\"><p>Tienes alguna duda?<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_223514a9 has_text_color\"><div class=\"wpb_wrapper\"><p>Preguntas frecuentes<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_77344615 has_text_color\"><div class=\"wpb_wrapper\"><p>Consulta las respuestas a las preguntas m\u00e1s frecuentes de los usuarios.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div>[vc_raw_html css=\u00bb%7B%22default%22%3A%7B%22text-align%22%3A%22right%22%2C%22width%22%3A%22210px%22%2C%22margin-top%22%3A%22-30px%22%2C%22margin-bottom%22%3A%2250px%22%2C%22position%22%3A%22relative%22%7D%7D\u00bb el_class=\u00bbfloat-right\u00bb]JTVCZmdjX2J1dHRvbiUyMFRleHQlM0QlMjJGQVElMjdzJTIyJTIwdXJsJTNEJTIyJTJGZXMlMkZmYXElMkYlMjIlNUQ=[\/vc_raw_html]<\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><div class=\"vc_col-sm-8 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_aa4000ee\"><div class=\"wpb_wrapper\">[vc_custom_heading text=\u00bbCONDICIONES DE USO\u00bb font_container=\u00bbtag:h1|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb el_class=\u00bbencabezado1&#8243;]<div class=\"wpb_text_column us_custom_a8290cda has_text_color\"><div class=\"wpb_wrapper\"><div><img decoding=\"async\" style=\"margin-right: 10px;\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/alert.png\" \/>Se proh\u00edbe viajar con patinetes y monociclos el\u00e9ctricos en los servicios de transporte de FGC: trenes, funiculares de Vallvidrera y Gelida, cremallera y funiculares de Montserrat, ni acceder o permanecer en las estaciones e instalaciones de FGC.<\/div>\n<\/div><\/div><div class=\"w-tabs layout_hor style_default switch_click toggle_style_1 has_scrolling\" style=\"--sections-title-size:1em;\"><div class=\"w-tabs-list items_2 align_justify\"><div class=\"w-tabs-list-h\"><button class=\"w-tabs-item active\" aria-controls=\"content-1521735053917-ccd4460c-f2b9\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Lineas Metropolitanas<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-1521735054150-31ffac58-a2b4\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Linea Lleida-La Pobla<\/span><\/button><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"1521735053917-ccd4460c-f2b9\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-1521735053917-ccd4460c-f2b9\" aria-expanded=\"true\"><div class=\"w-tabs-section-title\">Lineas Metropolitanas<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content us_custom_38ec8cf5\" id=\"content-1521735053917-ccd4460c-f2b9\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"86\" class=\"alignnone wp-image-5643 size-medium\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2018\/03\/pictograma-1-e1521819813404.jpg\" alt=\"icons 2\" srcset=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2018\/03\/pictograma-1-e1521819813404.jpg 488w, https:\/\/www.fgc.cat\/wp-content\/uploads\/2018\/03\/pictograma-1-e1521819813404-300x53.jpg 300w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/p>\n<ul>\n<li>Para viajar hay que adquirir y validar un billete adecuado para el trayecto a realizar antes de subir al tren o de acceder a los recintos delimitados. Tambi\u00e9n hay que validar el billete en caso de transbordo.<\/li>\n<li>El billete debe conservarse hasta que se salga de la estaci\u00f3n de destino para exhibirlo cuando lo solicite el personal de la empresa y para validarlo a la salida.<\/li>\n<li>El billete no es v\u00e1lido si ha sufrido alguna alteraci\u00f3n o manipulaci\u00f3n, o, cuando proceda, si no va acompa\u00f1ado del carn\u00e9 de identificaci\u00f3n o no corresponde a las condiciones espec\u00edficas de uso.<\/li>\n<li>El p\u00fablico usuario tiene derecho a utilizar, para hacer sus desplazamientos, el billete que m\u00e1s le convenga \u2014billete sencillo, tarjeta multiviaje, abono, etc.\u2014 y la obligaci\u00f3n de informarse, antes de adquirirlo, de las caracter\u00edsticas de cada billete. La alegaci\u00f3n de desconocimiento no exime al viajero de su responsabilidad.<\/li>\n<li>La validaci\u00f3n de un billete permite hacer un desplazamiento solo en una direcci\u00f3n.<\/li>\n<li>El billete sencillo adquirido en FGC solo se puede utilizar en las l\u00edneas de FGC, es decir, no permite el transbordo con otros medios de transporte.<\/li>\n<li>Los formatos, las condiciones y las tarifas de los billetes integrados (que llevan en el anverso las siglas ATM) as\u00ed como las condiciones de uso de los soportes sin contacto de la T-mobilitat, se planifican y aprueban desde la Autoridad del Transporte Metropolitano (ATM).<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-40476 size-medium\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2023\/12\/nous-pictogramas-2.png\" alt=\"\" \/><\/p>\n<ul>\n<li>El billete, ser\u00e1 v\u00e1lido hasta que haya un cambio de tarifas y, en cualquier caso, hasta la fecha que se determine.<\/li>\n<li>En caso de que la persona usuaria lleve un billete con indicios de haber sido manipulado o falsificado, le ser\u00e1 retirado y se le requerir\u00e1 la documentaci\u00f3n para cursar la denuncia correspondiente. Posteriormente, se indicar\u00e1 a la persona que abandone el tren o las dependencias.<\/li>\n<li>Los menores de 4 a\u00f1os pueden viajar gratuitamente si no ocupan asiento.<\/li>\n<li>Uso de los trenes escolares:\n<ul>\n<li>a) El uso de los trenes escolares est\u00e1 dirigido principalmente a escolares. La responsabilidad de permitir que los menores viajen solos recae en los padres\/tutores del menor.<\/li>\n<li>b) Personas que requieren una atenci\u00f3n especial, como por ejemplo aquellas con movilidad reducida, pueden acceder y ocupar los espacios destinados a estos colectivos dentro de los trenes escolares.<\/li>\n<\/ul>\n<\/li>\n<li>Se pueden llevar animales de compa\u00f1\u00eda gratuitamente siempre que la ocupaci\u00f3n de los trenes no modifique esta condici\u00f3n y se cumplan las condiciones establecidas en este texto. Los perros deben llevar bozal y deben ir sujetos con una correa desde el momento en que accedan a las instalaciones de FGC. Los animales peque\u00f1os deben viajar dentro de cestas o jaulas, pero en ning\u00fan caso pueden ocupar un asiento.Ser\u00e1 responsabilidad del titular del animal de compa\u00f1\u00eda cumplir con todas las obligaciones que se deriven de la tenencia de animales, de acuerdo con la Ley 7\/2023, de 28 de marzo, de bienestar animal.Los perros considerados potencialmente peligrosos por la Ley 10\/1999, de 30 de julio, no pueden ser conducidos en ning\u00fan caso por menores de 16 a\u00f1os, ni en los trenes ni en las estaciones (DOGC n\u00fam. 2948, de 09\/08\/1999).\n<p>De acuerdo con el Decreto 170\/2002 y el Real Decreto 287\/2002, la persona que los lleve debe portar la licencia y el certificado acreditativo de inscripci\u00f3n en el Registro Municipal, la correa debe tener una longitud inferior a 2 metros y no se puede llevar m\u00e1s de un perro por persona, sin perjuicio del cumplimiento de las dem\u00e1s obligaciones contempladas en la normativa aplicable.<\/p>\n<p>Los perros de asistencia tienen una consideraci\u00f3n diferenciada y no est\u00e1n condicionados a la ocupaci\u00f3n. Las personas propietarias deben llevar la acreditaci\u00f3n del animal para poder mostrarla si el personal de FGC la solicita.<\/p>\n<p>Existen cinco tipos diferentes de perros de asistencia:<\/p>\n<ul>\n<li>a. Perro gu\u00eda: adiestrado para guiar a personas con discapacidad visual o sordoceguera.<\/li>\n<li>b. Perro de servicio: adiestrado para prestar ayuda a personas con discapacidad f\u00edsica tanto en el entorno privado como en el p\u00fablico.<\/li>\n<li>c. Perro de se\u00f1alizaci\u00f3n de sonidos: adiestrado para avisar a personas sordas de distintos sonidos e indicar su procedencia.<\/li>\n<li>d. Perro de alerta m\u00e9dica: adiestrado para dar una alerta en caso de crisis epil\u00e9ptica, diab\u00e9tica u otras enfermedades reconocidas.<\/li>\n<li>e. Perro para personas con trastornos del espectro autista: adiestrado para cuidar de la integridad f\u00edsica de una persona con TEA.<\/li>\n<\/ul>\n<\/li>\n<li>Queda prohibido el acceso de patinetes i monociclos el\u00e9ctricos a los veh\u00edculos e instalaciones de FGC; las bicicletas se podr\u00e1n llevar gratuitamente en todos los trenes y funiculares todos los d\u00edas y se tendr\u00e1n que situar en los espacios destinados a tal efecto dentro del veh\u00edculo. Seg\u00fan la ocupaci\u00f3n de los trenes o funiculares, FGC puede variar estas condiciones.<\/li>\n<li>Las bicicletas s\u00f3lo se podr\u00e1n estacionar en las instalaciones de FGC en los espacios habilitados para hacerlo.<\/li>\n<li>El pasaje que viaje con equipaje tiene que usar la bandeja portaequipajes, y debe dejar libre los pasillos y las plataformas de los coches.<\/li>\n<li>Hay que respetar y, cuando proceda, ceder los asientos reservados a personas con movilidad reducida u otros colectivos especificados en la se\u00f1alizaci\u00f3n.<\/li>\n<li>Ante una incidencia en el servicio ferroviario de FGC con un retraso superior a 40 minutos, la persona usuaria tendr\u00e1 derecho a un t\u00edtulo de transporte igual al trayecto realizado que podr\u00e1 utilizar hasta el siguiente cambio de tarifas. La petici\u00f3n del canje puede solicitarla la persona usuaria mediante una reclamaci\u00f3n en cualquiera de las dependencias de FGC, v\u00eda correo electr\u00f3nico o canales telef\u00f3nicos, y acreditar el t\u00edtulo de transporte utilizado.<\/li>\n<li>FGC es un espacio donde se potencia la convivencia. Por ello, las personas usuarias deben mantener un comportamiento c\u00edvico, correcto y respetuoso con el resto de pasaje y el personal de FGC, y deben atender las indicaciones del personal de FGC, los indicadores de los carteles, los avisos de los trenes y las estaciones, y la megafon\u00eda.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"73\" class=\"alignnone wp-image-40479 size-medium\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2022\/05\/prohibit.png\" alt=\"prohibit\" srcset=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2022\/05\/prohibit.png 682w, https:\/\/www.fgc.cat\/wp-content\/uploads\/2022\/05\/prohibit-300x32.png 300w, https:\/\/www.fgc.cat\/wp-content\/uploads\/2022\/05\/prohibit-600x64.png 600w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><br \/>\n<strong>No est\u00e1 permitido:<\/strong><\/p>\n<ul>\n<li>Fumar en los trenes, los funiculares y en todas las instalaciones de FGC, tanto abiertas como cerradas.<\/li>\n<li>Acceder y circular con patinetes y monociclos el\u00e9ctricos en los veh\u00edculos y en las instalaciones de FGC.<\/li>\n<li>Circular con bicicletas y otros veh\u00edculos de movilidad personal (excepto sillas de ruedas) por los trenes e instalaciones de FGC. Atarlos en \u00e1rboles, se\u00f1ales, bancos y otros elementos de mobiliario o en lugares reservados para personas con movilidad reducida.<\/li>\n<li>Utilizar sin causa justificada los puntos de emergencia y ayuda instalados al lado de las m\u00e1quinas expendedoras de billetes o los andenes, los sistemas de parada de emergencia de las escaleras mec\u00e1nicas y los ascensores, y utilizar estos elementos de manera indebida; o utilizar sin causa justificada los aparatos de alarma de los trenes o impedir su uso leg\u00edtimo.<\/li>\n<li>Entrar o salir del tren despu\u00e9s de que haya sonado la se\u00f1al ac\u00fastica; entrar en las cabinas de conducci\u00f3n o las instalaciones reservadas para uso exclusivo del personal autorizado, bajar a las v\u00edas o entrar en los t\u00faneles, impedir o forzar la apertura o el cierre de las puertas de acceso a los trenes.<\/li>\n<li>Arrojar o depositar objetos en la v\u00eda o en sus inmediaciones.<\/li>\n<li>Introducir objetos o materiales que puedan ser peligrosos o molestos para los usuarios. Realizar actividades o acciones que puedan perturbar el pasaje, alterar el orden p\u00fablico o perturbar los servicios. Mantener un comportamiento que implique peligro para la integridad f\u00edsica propia o para el resto de pasaje, y realizar acciones que deterioren o ensucien los trenes o las instalaciones.<\/li>\n<li>Distribuir propaganda, pegar carteles, mendigar, organizar rifas o juegos de azar, vender u ofrecer bienes o servicios, o hacer cualquier clase de actividad art\u00edstica en los trenes y las instalaciones, sin la autorizaci\u00f3n de la empresa, tales como utilizar instrumentos musicales, etc.<\/li>\n<li>Consumir bebidas alcoh\u00f3licas (excepto en establecimientos autorizados) y sustancias t\u00f3xicas, en todo el \u00e1mbito de FGC.<\/li>\n<li>De acuerdo con la Ley 4\/2006, de 31 de marzo, ferroviaria, el incumplimiento de estas prohibiciones constituye una infracci\u00f3n que puede ser sancionada si se tipifica como leve con una multa de hasta 6.000 euros; si es grave, hasta 30.000 euros; y, si es muy grave, hasta 300.000 euros.<\/li>\n<\/ul>\n<p><strong>La percepci\u00f3n m\u00ednima establecida por el uso indebido del servicio es de 100\u20ac<\/strong><\/p>\n<p><strong>El pago inmediato de la percepci\u00f3n m\u00ednima tiene una bonificaci\u00f3n del 50%.<\/strong><\/p>\n<p><strong>Se considera que el viajero hace un uso indebido del servicio cuando:<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>El billete no se haya validado antes de viajar o de acceder a los recintos delimitados.<\/li>\n<li>No se disponga de billete o no se pueda mostrar cuando se requiera.<\/li>\n<li>El billete haya caducado o no sea v\u00e1lido.<\/li>\n<li>Se trate de un billete de un importe reducido y el viajero no pueda acreditar el derecho a obtenerlo.<\/li>\n<li>Se trate de un billete personalizado que no sea de su titularidad.<\/li>\n<li>El billete se utilice fuera de la zona tarifaria correspondiente.<\/li>\n<li>De acuerdo con el art. 52 la Ley 7\/2004, de 16 de julio, de medidas fiscales y administrativas, en relaci\u00f3n con la Ley 4\/2006, de 31 de marzo, ferroviaria, modificado por el art. 52 de la Ley 26\/2009, de 23 de diciembre y actualizado por Resoluci\u00f3n TES\/3013\/2011, de 21 de diciembre, viajar sin billete v\u00e1lido o suficiente y no efectuar el pago en el plazo indicado puede constituir una infracci\u00f3n administrativa sancionable con una multa de hasta 6.000 \u20ac, de acuerdo con los art. 65 y 66 de la Ley 4\/2006, de 31 de marzo, ferroviaria. Si el usuario se niega a identificarse se solicitar\u00e1 la presencia de los agentes de seguridad o del orden p\u00fablico.<\/li>\n<li>Los usuarios disponen de una versi\u00f3n completa de las Condiciones de utilizaci\u00f3n y de un Libro de reclamaciones en las estaciones.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div><div class=\"g-cols wpb_row us_custom_72fc42ef via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_1e38dc93\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top us_custom_c60307d2 align_center\" style=\"--hwrapper-gap:1.2rem\"><div class=\"wpb_text_column us_custom_8f8e3d9e has_text_color\"><div class=\"wpb_wrapper\"><p>Publicaci\u00f3n del DOGC<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container has-link\"><div class=\"vc_column-inner us_custom_a09327f0\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top us_custom_38f77d0b align_center\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-text us_custom_c311706f download-link has_text_color\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/dogc.gencat.cat\/es\/document-del-dogc\/?documentId=973455\" class=\"w-text-h\"><span class=\"w-text-value\">Consultar<\/span><\/a><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/combined-shape.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><\/div><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/dogc.gencat.cat\/es\/document-del-dogc\/index.html?documentId=1019975\" class=\"vc_column-link smooth-scroll\" aria-label=\"Enlace\"><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"1521735054150-31ffac58-a2b4\"><button class=\"w-tabs-section-header\" aria-controls=\"content-1521735054150-31ffac58-a2b4\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Linea Lleida-La Pobla<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content us_custom_38ec8cf5\" id=\"content-1521735054150-31ffac58-a2b4\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5643 size-medium\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2018\/03\/pictograma-1-e1521819813404.jpg\" alt=\"icons 5\" width=\"300\" height=\"86\" \/><\/p>\n<ul>\n<li>Para viajar, es necesario adquirir un billete adecuado para el trayecto que se desea realizar y validarlo. La compra de billetes se puede hacer en l\u00ednea, en la estaci\u00f3n de Balaguer o a bordo. Aquel pasajero que suba al tren sin billete deber\u00e1 solicitarlo al personal de intervenci\u00f3n en ruta.<\/li>\n<li>El billete debe conservarse hasta salir de la estaci\u00f3n de destino para exhibirlo cuando lo solicite el personal de la empresa en cualquier punto del trayecto.<\/li>\n<li>El billete no es v\u00e1lido si ha sufrido alguna alteraci\u00f3n o manipulaci\u00f3n o, cuando corresponda, si no va acompa\u00f1ado del carn\u00e9 de identificaci\u00f3n, o si no cumple con las condiciones espec\u00edficas de uso.<\/li>\n<li>El p\u00fablico usuario tiene derecho a utilizar el billete que m\u00e1s le convenga y la obligaci\u00f3n de informarse, antes de adquirirlo, sobre las caracter\u00edsticas de cada billete.<\/li>\n<li>Para adquirir los billetes, el p\u00fablico usuario dispone de la informaci\u00f3n adecuada sobre las zonas del trayecto en los paneles informativos.<\/li>\n<li>La validaci\u00f3n de un billete permite realizar un desplazamiento solo en una direcci\u00f3n.<\/li>\n<li>El billete sencillo no permite el transbordo con otros medios de transporte (Renfe, etc.).<\/li>\n<li>Los billetes integrados ATM permiten realizar transbordos sin penalizaci\u00f3n de viajes entre las diferentes empresas adheridas al Sistema Tarifario Integrado. Es obligatoria la validaci\u00f3n del billete en cada transbordo entre las diferentes empresas.<\/li>\n<li>Se pueden realizar un m\u00e1ximo de tres transbordos en un tiempo l\u00edmite horario desde la primera validaci\u00f3n hasta la \u00faltima, sin consumo adicional de viaje en el transbordo de:\n<ul>\n<li>1 hora y 15 minutos en trayectos de una zona.<\/li>\n<li>1 hora y 30 minutos en trayectos de 2 zonas.<\/li>\n<li>3 horas en trayectos de 3 zonas.<\/li>\n<li>4 horas y 15 minutos en trayectos de 4 zonas.<\/li>\n<\/ul>\n<\/li>\n<li>El billete ser\u00e1 v\u00e1lido hasta el pr\u00f3ximo cambio de tarifas.<\/li>\n<li>El uso indebido del servicio implicar\u00e1 el abono de una percepci\u00f3n m\u00ednima en los t\u00e9rminos y condiciones que establece la ley correspondiente.<\/li>\n<\/ul>\n<p><strong>La percepci\u00f3n m\u00ednima establecida por el uso indebido del servicio es de:<\/strong> 100\u20ac<\/p>\n<p>El pago de la percepci\u00f3n m\u00ednima tiene una bonificaci\u00f3n del 50% si se realiza dentro de las 48 horas siguientes, en d\u00edas h\u00e1biles. Los menores de 18 a\u00f1os tendr\u00e1n la bonificaci\u00f3n del 50% durante 30 d\u00edas.<\/p>\n<p><strong>Se considera que el viajero hace un uso indebido del servicio en los siguientes casos:<\/strong><\/p>\n<p>\u2013 El billete no se ha validado en el interior del tren o bien no ha regularizado su situaci\u00f3n de viajero\/a sin billete en el interior del tren ante el agente de intervenci\u00f3n en ruta.<\/p>\n<p>\u2013 No dispone del billete.<\/p>\n<p>\u2013 El billete ha caducado.<\/p>\n<p>\u2013 Se trata de un billete de importe reducido y el viajero no puede acreditar el derecho de obtenerlo.<\/p>\n<p>\u2013 Se trata de un billete personalizado que no es de titularidad suya.<\/p>\n<p>\u2013 El billete se usa fuera de la zona tarifaria correspondiente.<\/p>\n<p>\u2013 Se viaja con un t\u00edtulo de transporte que no es v\u00e1lido.<br \/>\nSi el viajero lleva un billete integrado correcto pero no validado en el transbordo, deber\u00e1 abonar el precio del billete sencillo de una zona.<br \/>\nEn caso de que el viajero lleve un billete con indicios de haber sido manipulado o falsificado se aplicar\u00e1 lo dispuesto en la correspondiente Ley Ferroviaria.<br \/>\nEn la estaci\u00f3n de Balaguer se encuentra un libro de objeciones a la percepci\u00f3n m\u00ednima a disposici\u00f3n del cliente. El plazo para rellenar una hoja de objeci\u00f3n es de 30 d\u00edas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-46921 size-medium\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2023\/12\/nous-pictogramas-2.png\" alt=\"Pictograma persones a qui es cedeix els seients reservats\" width=\"300\" height=\"44\" srcset=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2023\/12\/nous-pictogramas-2.png 385w, https:\/\/www.fgc.cat\/wp-content\/uploads\/2023\/12\/nous-pictogramas-2-300x44.png 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li>La posesi\u00f3n de un billete v\u00e1lido garantiza la prestaci\u00f3n del transporte, pero no la ocupaci\u00f3n de un asiento en el interior del tren. En ning\u00fan caso se podr\u00e1 ir sentado en las plataformas.<\/li>\n<li>Los menores de cuatro a\u00f1os pueden viajar gratuitamente siempre y cuando no ocupen asiento.<\/li>\n<li>Se pueden llevar animales de compa\u00f1\u00eda gratuitamente siempre que la ocupaci\u00f3n de los trenes no modifique esta condici\u00f3n y se cumplan las condiciones establecidas en este texto.<\/li>\n<li>Los perros deben llevar bozal y deben ir sujetos con una correa desde el momento en que accedan a las dependencias de FGC.<\/li>\n<li>Los animales peque\u00f1os deben viajar dentro de cestas o jaulas, pero en ning\u00fan caso pueden ocupar un asiento.<\/li>\n<li>Ser\u00e1 responsabilidad del titular del animal de compa\u00f1\u00eda cumplir con todas las obligaciones que se derivan de la tenencia de animales, de acuerdo con la ley 7\/2023, de 28 de marzo, de bienestar animal. Quien lleve perros considerados potencialmente peligrosos seg\u00fan la Ley 10\/1999, debe hacerlo seg\u00fan lo que establece la legislaci\u00f3n vigente.<\/li>\n<li>Los perros gu\u00eda tienen consideraci\u00f3n diferenciada y no quedan condicionados a la ocupaci\u00f3n.<\/li>\n<li>Se pueden transportar bicicletas gratuitamente, siempre que la ocupaci\u00f3n del tren lo permita.<\/li>\n<li>Los usuarios que viajen con equipaje deber\u00e1n usar la bandeja portaequipajes y dejar libres los pasillos y las plataformas de los coches.<\/li>\n<li>Se deber\u00e1 respetar y, en su caso, ceder los asientos reservados a personas con movilidad reducida u otros colectivos especificados en la se\u00f1alizaci\u00f3n.<\/li>\n<li>En caso de una incidencia en el servicio ferroviario de FGC con un retraso superior a 40 minutos, la persona usuaria tiene derecho a un t\u00edtulo de transporte igual al trayecto efectuado que puede utilizar hasta el siguiente cambio de tarifas.<\/li>\n<li>La persona usuaria puede solicitar el canje mediante una reclamaci\u00f3n en cualquiera de las dependencias de FGC, por correo electr\u00f3nico o canales telef\u00f3nicos, y acreditar el t\u00edtulo de transporte utilizado.<\/li>\n<li>FGC es un espacio donde se potencia la convivencia: se deber\u00e1 mantener siempre un comportamiento c\u00edvico y atender las indicaciones del personal de FGC, los carteles, los avisos y la megafon\u00eda.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6355 size-medium alignleft\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2022\/05\/prohibit-300x32.png\" alt=\"icons 7\" width=\"300\" height=\"58\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Con este fin queda totalmente PROHIBIDO:<\/strong><\/p>\n<ul>\n<li>Fumar en todas las instalaciones de FGC<\/li>\n<li>El acceso de patinetes y monociclos el\u00e9ctricos a los veh\u00edculos y a las instalaciones de FGC<\/li>\n<li>Circular con bicicletas, patines o similares por los recintos interiores, los vest\u00edbulos y los andenes. Atarlos en \u00e1rboles, se\u00f1ales, bancos y otros elementos de mobiliario o en lugares reservados para personas con movilidad reducida<\/li>\n<li>Utilizar sin causa justificada los puntos de informaci\u00f3n y ayuda o hacer un mal uso de ellos<\/li>\n<li>Entrar al tren o salir despu\u00e9s de que haya sonado la se\u00f1al ac\u00fastica<\/li>\n<li>Introducir objetos o materiales que puedan ser peligrosos o molestos<\/li>\n<li>Viajar en condiciones o en lugares inadecuados<\/li>\n<li>Acceder a los lugares no autorizados o bajar a la v\u00eda y acceder a los t\u00faneles<\/li>\n<li>Impedir o forzar la apertura o el cierre de las puertas de los trenes o manipular sus mecanismos<\/li>\n<li>Utilizar sin una causa justificada los aparatos de alarma de los trenes o impedir su uso leg\u00edtimo<\/li>\n<li>Realizar actividades o acciones que puedan perturbar o alterar el orden p\u00fablico o los servicios de FGC<\/li>\n<li>Mantener un comportamiento que implique un peligro para la integridad f\u00edsica propia o para el resto de pasajeros<\/li>\n<li>Realizar acciones que deterioren o ensucien los trenes o las instalaciones<\/li>\n<li>Permanecer en las instalaciones fuera del horario previsto<\/li>\n<li>Manipular, destruir o deteriorar cualquier elemento relacionado con la circulaci\u00f3n y el servicio en general<\/li>\n<li>Lanzar o depositar objetos en la v\u00eda o en sus alrededores<\/li>\n<li>Utilizar sin justificaci\u00f3n las rutas de evacuaci\u00f3n y\/o salidas de emergencia u obstaculizarlas<\/li>\n<li>Mendigar y realizar cualquier clase de actividad art\u00edstica o comercial en los trenes y las instalaciones, sin la autorizaci\u00f3n de la empresa<\/li>\n<li>Consumir bebidas alcoh\u00f3licas (excepto en establecimientos autorizados) y sustancias t\u00f3xicas, en todo el \u00e1mbito de FGC<\/li>\n<\/ul>\n<p>El incumplimiento de estas prohibiciones constituir\u00e1 una infracci\u00f3n de conformidad con la Ley 4\/2006, de 31 de marzo, Ferroviaria, que puede ser sancionada si se tipifica como leve con una multa de hasta 6.000 euros; si se tipifica como grave, de hasta 30.000 euros, y si es muy grave, de hasta 300.000 euros.<\/p>\n<p><strong>Los usuarios disponen de una versi\u00f3n completa de las Condiciones de utilizaci\u00f3n publicadas en el DOGC n\u00fam. 9119, del 11 de marzo de 2024. En la estaci\u00f3n de Balaguer (calle de la Noguera Pallaresa s\/n, 25600 Balaguer) hay un libro de reclamaciones a disposici\u00f3n de los viajeros. Asimismo, las reclamaciones o sugerencias se pueden cursar mediante la p\u00e1gina web de FGC.<\/strong><\/p>\n<\/div><\/div><div class=\"g-cols wpb_row us_custom_72fc42ef via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_1e38dc93\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top us_custom_c60307d2 align_center\" style=\"--hwrapper-gap:1.2rem\"><div class=\"wpb_text_column us_custom_8f8e3d9e has_text_color\"><div class=\"wpb_wrapper\"><p>Publicaci\u00f3n del DOGC<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container has-link\"><div class=\"vc_column-inner us_custom_a09327f0\"><div class=\"wpb_wrapper\"><div class=\"w-hwrapper valign_top us_custom_38f77d0b align_center\" style=\"--hwrapper-gap:1.20rem\"><div class=\"w-text us_custom_c311706f download-link has_text_color\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/dogc.gencat.cat\/es\/document-del-dogc\/?documentId=980441\" class=\"w-text-h\"><span class=\"w-text-value\">Consultar<\/span><\/a><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/05\/combined-shape.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><\/div><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/dogc.gencat.cat\/es\/document-del-dogc\/index.html?documentId=1019966\" class=\"vc_column-link smooth-scroll\" aria-label=\"Enlace\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_8965dd23 container formulari_responsive height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style data-type=\"us_custom-css\">.titol-centres h2{color:#2b3d3f;text-align:center;font-size:33px;line-height:1.23;font-weight:700}<\/style><section class=\"l-section wpb_row us_custom_82104407 link_drank_gree height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_9ab4437c\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_5cdef65a titol-centres has_text_color\"><div class=\"wpb_wrapper\"><h2>Centros de atenci\u00f3n al cliente<\/h2>\n<\/div><\/div><div class=\"g-cols wpb_row us_custom_9ffd512c via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_72565e22\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_88a6b76c has_text_color\"><div class=\"wpb_wrapper\"><h3><img decoding=\"async\" style=\"vertical-align: middle; margin-right: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/comunic.png\" alt=\"\" \/>Pla\u00e7a Catalunya<\/h3>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Ubicaci\u00f3n<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7071ba1f has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">Situado al vest\u00edbulo junto a la calle Bergara de la estaci\u00f3n de Pla\u00e7a Catalunya. El acceso para personas con movilidad reducida (PMR) por el ascensor situado en la calle de Bergara, n.\u00ba 7, cruce con calle de Balmes.<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Horario<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7366f3f5 has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">De 8 a 20 h<br \/>\n(de Lunes a Viernes laborables)<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_52622ec3 has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/citaprevia.fgc.cat\/fgc\/?idioma=es_ES&amp;id_oficina_sele=1#nbb\">Pedir cita previa<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"\" \/><\/a><\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_c97ae674 has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/goo.gl\/maps\/aSbmMAXEq7mxWbMAA\">Consulta la ubicaci\u00f3n en Google Maps<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"\" \/><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_54cf9f5b\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_88a6b76c has_text_color\"><div class=\"wpb_wrapper\"><h3><img decoding=\"async\" style=\"vertical-align: middle; margin-right: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/comunic.png\" alt=\"\" \/>Pla\u00e7a Espanya<\/h3>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Ubicaci\u00f3n<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7071ba1f has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">Se encuentra situado en el vest\u00edbulo junto a la Gran Via de les Corts Catalanes de la estaci\u00f3n de Pla\u00e7a Espanya. El acceso para personas con movilidad reducida (PMR) se realiza mediante el ascensor ubicado en Pla\u00e7a Espanya, n\u00fam. 1, en la intersecci\u00f3n con la Gran Via de les Corts Catalanes, junto a la Fira de Montju\u00efc.<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Horario<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7071ba1f has_text_color\"><div class=\"wpb_wrapper\"><p>De 9 a 19 h. (de lunes a viernes)<\/p>\n<p>Agosto: De 9 a 14 h. (de lunes a viernes)<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_752aeae6 has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/citaprevia.fgc.cat\/fgc\/?idioma=es_ES&amp;id_oficina_sele=0#nbb\">Pedir cita previa<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"\" \/><\/a><\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_c97ae674 has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/goo.gl\/maps\/ZAfRnM6rnZSTyeoy9\">Consulta la ubicaci\u00f3n en Google Maps<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"\" \/><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row us_custom_9ffd512c via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_e5a6eb2b\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_41cd0d95 has_text_color\"><div class=\"wpb_wrapper\"><h3><img decoding=\"async\" style=\"vertical-align: middle; margin-right: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/comunic.png\" alt=\"\" \/>Estaci\u00f3 de Balaguer<\/h3>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Ubicaci\u00f3n<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7071ba1f has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">Se encuentra situado en el vest\u00edbulo de la estaci\u00f3n de Balaguer. El acceso para personas con movilidad reducida (PMR) se realiza mediante la rampa de acceso directo desde la calle Noguera Pallaresa, n\u00fam. 1 de Balaguer.<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Horario<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7366f3f5 has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">De 8 a 20 h<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_cf4dec5e has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"underlined\" href=\"mailto:ccbalaguer@fgc.cat\">ccbalaguer@fgc.cat<\/a><\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_5cb29c3b has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/goo.gl\/maps\/NvpUDXXQvJ9dqYge8\">Consulta la ubicaci\u00f3n en Google Maps<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"\" \/><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_54cf9f5b\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_88a6b76c has_text_color\"><div class=\"wpb_wrapper\"><h3><img decoding=\"async\" style=\"vertical-align: middle; margin-right: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/comunic.png\" alt=\"\" \/>Oficina de Confecci\u00f3n de Carnets de Pensionista de FGC<\/h3>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Ubicaci\u00f3n<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7071ba1f has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">Servicio exclusivo de tramitaci\u00f3n del Carnet de Pensionista de FGC. El acceso es directo desde la calle Avenir, 6 de Barcelona.<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_49b00f61 has_text_color\"><div class=\"wpb_wrapper\"><p>Horario<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_7071ba1f has_text_color\"><div class=\"wpb_wrapper\"><div class=\"value\">9:00-13:45h \/ 15:00-18:30h<br \/>\n(de Lunes a Viernes laborables)<\/div>\n<\/div><\/div><div class=\"wpb_text_column us_custom_421c19ab has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/webcitaprevia.es\/citasWeb.fgc\/citas.php?Lang=2\" target=\"_blank\" rel=\"noopener\">Pedir cita previa<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"cita previa\" \/><\/a><\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_c97ae674 has_text_color\"><div class=\"wpb_wrapper\"><p><a class=\"link-item\" href=\"https:\/\/www.google.es\/maps\/place\/Carrer+de+l'Avenir,+6,+08006+Barcelona\/@41.3976281,2.1473923,17z\/data=!4m5!3m4!1s0x12a4a29ec90acff7:0xd215997652984e3c!8m2!3d41.3976593!4d2.1495903\" target=\"_blank\" rel=\"noopener noreferrer\">Consulta la ubicaci\u00f3n en Google Maps<img decoding=\"async\" style=\"vertical-align: middle; margin-left: 10px;\" src=\"\/wp-content\/uploads\/2020\/05\/right-1.png\" alt=\"\" \/><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_empty_space]<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Portada \u00bfEN QU\u00c9 OS PODEMOS AYUDAR? Formulario de Consultas Formulario de Quejas y reclamaciones Formulario de Sugerencias y agradecimientos Centros de atenci\u00f3n al cliente Justificante de retraso Preguntas frecuentes Condiciones de uso Pago de percepciones m\u00ednimas Acceso al tr\u00e1mite de peticiones gen\u00e9ricas de la Generalitat de Catalunya Tienes alguna duda? Preguntas frecuentes Consulta las respuestas...","protected":false},"author":1,"featured_media":0,"parent":2723,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2773","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Condiciones de uso de billetes y trenes - FGC<\/title>\n<meta name=\"description\" content=\"Consulta las condiciones de uso de los billetes de los Ferrocarrils de la Generalitat de Catalunya y toda la informaci\u00f3n sobre las normas en los trenes FGC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condiciones de uso\" \/>\n<meta property=\"og:description\" content=\"Consulta las condiciones de uso de los billetes de los Ferrocarrils de la Generalitat de Catalunya y toda la informaci\u00f3n sobre las normas en los trenes FGC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferrocarrils de la Generalitat de Catalunya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fgcferrocarrils\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T12:46:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/alert.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FGC\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/\",\"name\":\"Condiciones de uso de billetes y trenes - FGC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/alert.png\",\"datePublished\":\"2017-08-15T18:21:11+00:00\",\"dateModified\":\"2025-07-21T12:46:14+00:00\",\"description\":\"Consulta las condiciones de uso de los billetes de los Ferrocarrils de la Generalitat de Catalunya y toda la informaci\u00f3n sobre las normas en los trenes FGC.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/alert.png\",\"contentUrl\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/alert.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/condiciones-de-uso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atenci\u00f3n al Cliente\",\"item\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/atencion-al-cliente\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Condiciones de uso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/\",\"name\":\"FGC\",\"description\":\"Ferrocarrils de la Generalitat de Catalunya\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#organization\",\"name\":\"Ferrocarrils de la Generalitat de Catalunya\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-FGC-square.png\",\"contentUrl\":\"https:\\\/\\\/www.fgc.cat\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-FGC-square.png\",\"width\":1024,\"height\":1024,\"caption\":\"Ferrocarrils de la Generalitat de Catalunya\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fgc.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fgcferrocarrils\",\"https:\\\/\\\/x.com\\\/FGC\",\"https:\\\/\\\/www.instagram.com\\\/fgc.cat\\\/?hl=es\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/FGCferrocarrils\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Condiciones de uso de billetes y trenes - FGC","description":"Consulta las condiciones de uso de los billetes de los Ferrocarrils de la Generalitat de Catalunya y toda la informaci\u00f3n sobre las normas en los trenes FGC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/","og_locale":"es_ES","og_type":"article","og_title":"Condiciones de uso","og_description":"Consulta las condiciones de uso de los billetes de los Ferrocarrils de la Generalitat de Catalunya y toda la informaci\u00f3n sobre las normas en los trenes FGC.","og_url":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/","og_site_name":"Ferrocarrils de la Generalitat de Catalunya","article_publisher":"https:\/\/www.facebook.com\/fgcferrocarrils","article_modified_time":"2025-07-21T12:46:14+00:00","og_image":[{"url":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/alert.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@FGC","twitter_misc":{"Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/","url":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/","name":"Condiciones de uso de billetes y trenes - FGC","isPartOf":{"@id":"https:\/\/www.fgc.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/#primaryimage"},"image":{"@id":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/alert.png","datePublished":"2017-08-15T18:21:11+00:00","dateModified":"2025-07-21T12:46:14+00:00","description":"Consulta las condiciones de uso de los billetes de los Ferrocarrils de la Generalitat de Catalunya y toda la informaci\u00f3n sobre las normas en los trenes FGC.","breadcrumb":{"@id":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/#primaryimage","url":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/alert.png","contentUrl":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/alert.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/condiciones-de-uso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fgc.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Atenci\u00f3n al Cliente","item":"https:\/\/www.fgc.cat\/es\/atencion-al-cliente\/"},{"@type":"ListItem","position":3,"name":"Condiciones de uso"}]},{"@type":"WebSite","@id":"https:\/\/www.fgc.cat\/es\/#website","url":"https:\/\/www.fgc.cat\/es\/","name":"FGC","description":"Ferrocarrils de la Generalitat de Catalunya","publisher":{"@id":"https:\/\/www.fgc.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fgc.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fgc.cat\/es\/#organization","name":"Ferrocarrils de la Generalitat de Catalunya","url":"https:\/\/www.fgc.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fgc.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/logo-FGC-square.png","contentUrl":"https:\/\/www.fgc.cat\/wp-content\/uploads\/2020\/06\/logo-FGC-square.png","width":1024,"height":1024,"caption":"Ferrocarrils de la Generalitat de Catalunya"},"image":{"@id":"https:\/\/www.fgc.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fgcferrocarrils","https:\/\/x.com\/FGC","https:\/\/www.instagram.com\/fgc.cat\/?hl=es","http:\/\/www.youtube.com\/user\/FGCferrocarrils"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:50:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/pages\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/comments?post=2773"}],"version-history":[{"count":50,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/pages\/2773\/revisions"}],"predecessor-version":[{"id":55039,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/pages\/2773\/revisions\/55039"}],"up":[{"embeddable":true,"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/pages\/2723"}],"wp:attachment":[{"href":"https:\/\/www.fgc.cat\/es\/wp-json\/wp\/v2\/media?parent=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}